{"id":7141,"date":"2026-01-30T11:16:12","date_gmt":"2026-01-30T10:16:12","guid":{"rendered":"https:\/\/spieker-jaeger.de\/berater\/justus-neuhaeuser\/"},"modified":"2026-01-30T12:17:37","modified_gmt":"2026-01-30T11:17:37","slug":"justus-neuhaeuser","status":"publish","type":"berater","link":"https:\/\/spieker-jaeger.de\/en\/advisor\/justus-neuhaeuser\/","title":{"rendered":"Justus Neuh\u00e4user"},"featured_media":7142,"menu_order":250,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"class_list":["post-7141","berater","type-berater","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/spieker-jaeger.de\/en\/wp-json\/wp\/v2\/berater\/7141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spieker-jaeger.de\/en\/wp-json\/wp\/v2\/berater"}],"about":[{"href":"https:\/\/spieker-jaeger.de\/en\/wp-json\/wp\/v2\/types\/berater"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spieker-jaeger.de\/en\/wp-json\/wp\/v2\/media\/7142"}],"wp:attachment":[{"href":"https:\/\/spieker-jaeger.de\/en\/wp-json\/wp\/v2\/media?parent=7141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}